{"id":785,"date":"2024-04-24T09:08:50","date_gmt":"2024-04-24T07:08:50","guid":{"rendered":"https:\/\/staging.meetmeat.be\/rgpd\/"},"modified":"2024-05-06T11:44:55","modified_gmt":"2024-05-06T09:44:55","slug":"rgpd","status":"publish","type":"page","link":"https:\/\/meetmeat.be\/fr\/rgpd\/","title":{"rendered":"Rgpd"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"785\" class=\"elementor elementor-785 elementor-384\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2496211 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2496211\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c6ff8b0\" data-id=\"3c6ff8b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-791a467 home-title elementor-widget elementor-widget-heading\" data-id=\"791a467\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Meet Meat<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40dd13ad elementor-widget elementor-widget-heading\" data-id=\"40dd13ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">RGPD<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24f99828 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24f99828\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e70b3e\" data-id=\"2e70b3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77183b20 elementor-widget elementor-widget-heading\" data-id=\"77183b20\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"cgu\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I. Conditions g\u00e9n\u00e9rales d'utilisation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bedba6d elementor-widget elementor-widget-text-editor\" data-id=\"5bedba6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mise \u00e0 jour le: 01\/04\/2024<\/p><h3>1. Champ d&rsquo;application<\/h3><p>Les pr\u00e9sentes conditions g\u00e9n\u00e9rales d&rsquo;utilisation (ci-apr\u00e8s les \u00ab\u00a0CGU\u00a0\u00bb) sont conclues par :<\/p><p>Noryel S.R.L. ayant son si\u00e8ge social \u00e0 124 rue Stevin, 1000 Brussels, enregistr\u00e9 \u00e0 la BCE sous le num\u00e9ro BE 0438.595.396, ci-apr\u00e8s d\u00e9nomm\u00e9 Meet Meat<\/p><p>et s&rsquo;appliquent \u00e0 toute visite ou utilisation du site internet meatmeat.be (ci-apr\u00e8s \u00ab\u00a0Plateforme\u00a0\u00bb) et de ses informations par un internaute (ci-apr\u00e8s \u00ab\u00a0Utilisateur\u00a0\u00bb).<\/p><p>En visitant ou utilisant la Plateforme, l&rsquo;Utilisateur reconnait avoir pris connaissance des pr\u00e9sentes CGU et accepte express\u00e9ment les droits et obligations qui y sont mentionn\u00e9s.<\/p><p>Il peut exceptionnellement \u00eatre d\u00e9rog\u00e9 aux dispositions des CGU par un accord \u00e9crit. Ces d\u00e9rogations peuvent consister en la modification, l&rsquo;ajout ou la suppression des clauses auxquelles elles se rapportent et n&rsquo;ont aucune incidence sur l&rsquo;application des autres dispositions des CGU.<\/p><p>Nous nous r\u00e9servons le droit de modifier nos CGU \u00e0 tout moment, sans notification pr\u00e9alable, mais nous nous engageons \u00e0 appliquer les dispositions qui \u00e9taient en vigueur au moment o\u00f9 vous avez utilis\u00e9 notre Plateforme.<\/p><h3>2. Plateforme<\/h3><h4>a. Acc\u00e8s et navigation<\/h4><p>Nous prenons toutes les mesures raisonnables et n\u00e9cessaires pour assurer le bon fonctionnement, la s\u00e9curit\u00e9 et l&rsquo;accessibilit\u00e9 de notre Plateforme. Toutefois, nous ne pouvons pas offrir de garantie d&rsquo;op\u00e9rabilit\u00e9 absolue et il faut d\u00e8s lors consid\u00e9rer nos actions comme \u00e9tant couvertes par une obligation de moyen.<\/p><p>Toute utilisation de la Plateforme se fait toujours aux propres risques de l&rsquo;Utilisateur. Ainsi, nous ne sommes pas responsables des dommages pouvant r\u00e9sulter de possibles dysfonctionnements, interruptions, d\u00e9fauts ou encore d&rsquo;\u00e9l\u00e9ments nuisibles pr\u00e9sents sur la Plateforme.<\/p><p>Nous nous r\u00e9servons le droit de restreindre l&rsquo;acc\u00e8s \u00e0 la Plateforme ou d&rsquo;interrompre son fonctionnement \u00e0 tout moment, sans obligation de notification pr\u00e9alable.<\/p><h4>b. Contenu<\/h4><p>Meet Meat d\u00e9termine en grande partie le contenu de la Plateforme et prend grand soin des informations pr\u00e9sentes sur celle-ci. Nous prenons toutes les mesures possibles pour maintenir notre Plateforme aussi compl\u00e8te, pr\u00e9cise et \u00e0 jour que possible, m\u00eame lorsque les informations pr\u00e9sentes sur celle-ci sont fournies par des tiers. Nous nous r\u00e9servons le droit de modifier, compl\u00e9ter ou supprimer \u00e0 tout moment la Plateforme et son contenu, sans que sa responsabilit\u00e9 ne puisse \u00eatre engag\u00e9e.<\/p><p>Meet Meat ne peut pas offrir de garantie absolue concernant la qualit\u00e9 de l&rsquo;information pr\u00e9sente sur la Plateforme. Il est donc possible que cette information ne soit pas toujours compl\u00e8te, exacte, suffisamment pr\u00e9cise ou \u00e0 jour. Par cons\u00e9quent, Meet Meat ne pourra pas \u00eatre tenue responsable des dommages, directs ou indirects, que l&rsquo;Utilisateur subirait de par l&rsquo;information pr\u00e9sente sur la Plateforme.<\/p><p>Si certains contenus de la Plateforme sont en violation avec la loi ou les droits des tiers, ou sont contraires \u00e0 la morale, nous vous demandons de nous en informer le plus rapidement possible par mail afin que nous puissions prendre des mesures appropri\u00e9es.<\/p><p>Tout t\u00e9l\u00e9chargement \u00e0 partir de la Plateforme a toujours lieu aux risques de l&rsquo;Utilisateur. Meet Meat ne pourra pas \u00eatre tenue responsable des \u00e9ventuels dommages, directs ou indirects, d\u00e9coulant de ces t\u00e9l\u00e9chargements, tels qu&rsquo;une perte de donn\u00e9es ou un endommagement du syst\u00e8me informatique de l&rsquo;Utilisateur, qui rel\u00e8vent enti\u00e8rement et exclusivement de la responsabilit\u00e9 de ce dernier.<\/p><h4>c. Services r\u00e9serv\u00e9s aux Utilisateurs inscrits<\/h4><p><em>1) Inscription<\/em><\/p><p>L&rsquo;acc\u00e8s \u00e0 certains services est conditionn\u00e9 par l&rsquo;inscription de l&rsquo;Utilisateur.<\/p><p>L&rsquo;inscription et l&rsquo;acc\u00e8s aux services de la Plateforme sont r\u00e9serv\u00e9s exclusivement aux personnes physiques ou morale, particulier ou professionnel, capables juridiquement, ayant rempli et valid\u00e9 le formulaire d&rsquo;inscription disponible en ligne sur la Plateforme ainsi que les pr\u00e9sentes CGU.<\/p><p>Lors de son inscription, l&rsquo;Utilisateur s&rsquo;engage \u00e0 fournir des informations exactes, sinc\u00e8res et \u00e0 jour sur sa personne et son \u00e9tat civil. L&rsquo;Utilisateur devra en outre proc\u00e9der \u00e0 une v\u00e9rification r\u00e9guli\u00e8re des donn\u00e9es le concernant afin d&rsquo;en conserver l&rsquo;exactitude.<\/p><p>L&rsquo;Utilisateur doit ainsi fournir imp\u00e9rativement une adresse e-mail valide, sur laquelle la Plateforme lui adressera une confirmation de son inscription \u00e0 ses services. Une adresse de messagerie \u00e9lectronique ne peut \u00eatre utilis\u00e9e plusieurs fois pour s&rsquo;inscrire aux services.<\/p><p>Toute communication r\u00e9alis\u00e9e par la Plateforme et ses partenaires est en cons\u00e9quence r\u00e9put\u00e9e avoir \u00e9t\u00e9 r\u00e9ceptionn\u00e9e et lue par l&rsquo;Utilisateur. Ce dernier s&rsquo;engage donc \u00e0 consulter r\u00e9guli\u00e8rement les messages re\u00e7us sur cette adresse e-mail et, le cas \u00e9ch\u00e9ant, \u00e0 r\u00e9pondre dans un d\u00e9lai raisonnable.<\/p><p>Une seule inscription est admise par personne physique ou morale, particulier ou professionnel.<\/p><p>L&rsquo;Utilisateur se voit attribuer un identifiant lui permettant d&rsquo;acc\u00e9der \u00e0 un espace dont l&rsquo;acc\u00e8s lui est r\u00e9serv\u00e9 (ci-apr\u00e8s \u00ab\u00a0Espace personnel\u00a0\u00bb), en compl\u00e9ment de la saisie de son mot de passe.<\/p><p>L&rsquo;identifiant est d\u00e9finitif, en revanche le mot de passe est modifiable en ligne par l&rsquo;Utilisateur dans son Espace personnel. Le mot de passe est personnel et confidentiel, l&rsquo;Utilisateur s&rsquo;engage ainsi \u00e0 ne pas le communiquer \u00e0 des tiers.<\/p><p>Meet Meat se r\u00e9serve en tout \u00e9tat de cause la possibilit\u00e9 de refuser une demande d&rsquo;inscription aux services de la Plateforme en cas de non-respect par l&rsquo;Utilisateur des CGU.<\/p><p><em>2) D\u00e9sinscription<\/em><\/p><p>L&rsquo;Utilisateur r\u00e9guli\u00e8rement inscrit pourra \u00e0 tout moment demander sa d\u00e9sinscription en se rendant sur la page d\u00e9di\u00e9e dans son Espace personnel. Toute d\u00e9sinscription de la Plateforme sera effective dans les plus brefs d\u00e9lais apr\u00e8s que l&rsquo;Utilisateur ait rempli le formulaire pr\u00e9vu \u00e0 cet effet.<\/p><h4>d. Contenu publi\u00e9 par l&rsquo;Utilisateur<\/h4><p>L&rsquo;utilisateur s&rsquo;engage au respect des lois en vigueur \u00e0 travers chacune de ses publications sur la Plateforme. Il sera particuli\u00e8rement attentif aux int\u00e9r\u00eats des tiers, au contenu \u00e0 caract\u00e8re offensant ainsi qu&rsquo;au contenu susceptible d&rsquo;\u00eatre contraire \u00e0 l&rsquo;ordre public ou au moeurs. L&rsquo;Utilisateur demeure responsable de tout contenu publi\u00e9 sur la Plateforme.<\/p><p>La Plateforme peut exercer une mod\u00e9ration sur toute publication et refuser la mise en ligne de contenu sans devoir fournir de justification. Au m\u00eame titre, le contenu publi\u00e9 par un Utilisateur pourra \u00eatre modifi\u00e9 ou supprim\u00e9 sans motif ni d\u00e9lai.<\/p><p>En publiant sur la Plateforme, l&rsquo;Utilisateur c\u00e8de gratuitement et \u00e0 titre non exclusif \u00e0 Meet Meat le droit de repr\u00e9senter, reproduire, adapter, modifier, distribuer et diffuser, directement ou indirectement ainsi que sur tout support et dans le monde entier le contenu publi\u00e9.<\/p><h3>3. Liens vers d&rsquo;autres sites internet<\/h3><p>La Plateforme pourrait contenir des liens ou hyperliens renvoyant vers des sites internet externes. De tels liens ne signifient pas de mani\u00e8re automatique qu&rsquo;il existe une relation entre Meet Meat et le site internet externe ou m\u00eame qu&rsquo;un accord implicite existe avec le contenu de ces sites externes.<\/p><p>Meet Meat n&rsquo;exerce aucun contr\u00f4le sur les sites internet externes. Nous ne sommes donc pas responsables du fonctionnement s\u00fbr et correct des hyperliens et de leur destination finale. D\u00e8s l&rsquo;instant o\u00f9 l&rsquo;Utilisateur clique sur l&rsquo;hyperlien, il quitte la Plateforme. Nous ne pouvons d\u00e8s lors pas \u00eatre tenus responsables en cas de dommage ult\u00e9rieur.<\/p><h3>4. Propri\u00e9t\u00e9 intellectuelle<\/h3><p>La structuration de la Plateforme, mais aussi les textes, graphiques, images, photographies, sons, vid\u00e9os, bases de donn\u00e9es, applications informatiques, etc. qui le composent ou qui sont accessibles via la Plateforme sont la propri\u00e9t\u00e9 de l&rsquo;\u00e9diteur et sont prot\u00e9g\u00e9s comme tels par les lois en vigueur au titre de la propri\u00e9t\u00e9 intellectuelle.<\/p><p>Toute repr\u00e9sentation, reproduction, adaptation ou exploitation partielle ou totale des contenus, marques d\u00e9pos\u00e9es et services propos\u00e9s par la Plateforme, par quelque proc\u00e9d\u00e9 que ce soit, sans l&rsquo;autorisation pr\u00e9alable, expresse et \u00e9crite de l&rsquo;\u00e9diteur, est strictement interdite, \u00e0 l&rsquo;exception des \u00e9l\u00e9ments express\u00e9ment d\u00e9sign\u00e9s comme libres de droits sur la Plateforme.<\/p><p>L&rsquo;Utilisateur de la Plateforme se voit octroyer un droit limit\u00e9 d&rsquo;acc\u00e8s, d&rsquo;utilisation et d&rsquo;affichage de la Plateforme et de son contenu. Ce droit est accord\u00e9 \u00e0 titre non exclusif, non transf\u00e9rable et ne peut \u00eatre utilis\u00e9 que moyennant un usage personnel et non commercial. Sauf accord pr\u00e9alable et \u00e9crit, les Utilisateurs ne sont pas autoris\u00e9s \u00e0 modifier, reproduire, traduire, distribuer, vendre, communiquer au public, en tout ou en partie, les \u00e9l\u00e9ments prot\u00e9g\u00e9s.<\/p><p>Il est interdit \u00e0 l&rsquo;Utilisateur d&rsquo;introduire des donn\u00e9es sur la Plateforme qui modifieraient ou qui seraient susceptibles d&rsquo;en modifier le contenu ou l&rsquo;apparence.<\/p><h3>5. Protection des donn\u00e9es personnelles<\/h3><p>Les donn\u00e9es personnelles fournies par l&rsquo;Utilisateur lors de sa visite ou de l&rsquo;utilisation de la Plateforme sont collect\u00e9es et trait\u00e9es par Meet Meat exclusivement \u00e0 des fins internes. Meet Meat assure \u00e0 ses utilisateurs qu&rsquo;elle attache la plus grande importance \u00e0 la protection de leur vie priv\u00e9e et de leurs donn\u00e9es personnelles, et qu&rsquo;elle s&rsquo;engage toujours \u00e0 communiquer de mani\u00e8re claire et transparente sur ce point.<\/p><p>Meet Meat s&rsquo;engage \u00e0 respecter la l\u00e9gislation applicable en la mati\u00e8re, \u00e0 savoir la Loi du 8 d\u00e9cembre 1992 relative \u00e0 la protection de la vie priv\u00e9e \u00e0 l&rsquo;\u00e9gard des traitements de donn\u00e9es \u00e0 caract\u00e8re personnel ainsi que le R\u00e8glement europ\u00e9en du 27 avril 2016 relatif \u00e0 la protection des personnes physiques \u00e0 l&rsquo;\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel et \u00e0 la libre circulation de ces donn\u00e9es.<\/p><p>Les donn\u00e9es personnelles de l&rsquo;Utilisateur sont trait\u00e9es conform\u00e9ment \u00e0 la <a href=\"\/rgpd\/#confidentialite\">politique de confidentialit\u00e9<\/a> disponible sur la Plateforme.<\/p><h3>6. Dispositions g\u00e9n\u00e9rales<\/h3><p>Meet Meat se r\u00e9serve la possibilit\u00e9 de modifier, \u00e9tendre, supprimer, limiter ou interrompre la Plateforme et les services associ\u00e9s \u00e0 tout moment, sans notification pr\u00e9alable, et sans engager sa responsabilit\u00e9.<\/p><p>En cas de violation des CGU par l&rsquo;Utilisateur, Meet Meat se r\u00e9serve le droit de prendre des mesures de sanction et de r\u00e9paration adapt\u00e9es. Meet Meat se r\u00e9serve notamment le droit de refuser \u00e0 l&rsquo;Utilisateur tout acc\u00e8s \u00e0 la Plateforme ou \u00e0 nos services temporairement ou d\u00e9finitivement. Ces mesures peuvent \u00eatre prises sans indication de motif et sans pr\u00e9avis. Elles ne peuvent pas engager la responsabilit\u00e9 de Meet Meat ou donner lieu \u00e0 une quelconque forme d&rsquo;indemnisation.<\/p><p>L&rsquo;ill\u00e9galit\u00e9 ou la nullit\u00e9 totale ou partielle d&rsquo;une disposition de nos CGU n&rsquo;aura aucun impact sur la validit\u00e9 et l&rsquo;application des autres dispositions. Nous disposons, dans un tel cas, du droit de remplacer la disposition par une autre disposition valable et de port\u00e9e similaire.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22e0ef3b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22e0ef3b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a2d1936\" data-id=\"1a2d1936\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d2a89 elementor-widget elementor-widget-heading\" data-id=\"4d2a89\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"cookies\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">II. Cookies<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4752fdac elementor-widget elementor-widget-text-editor\" data-id=\"4752fdac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column wpb_content_element \"><div class=\"wpb_wrapper\"><p style=\"text-align: justify;\">Notre site utilise des cookies strictement n\u00e9cessaires pour le bon fonctionnement de certains modules.<\/p><h3 style=\"text-align: justify;\">Google Analytics<\/h3><p style=\"text-align: justify;\">Ils sont \u00e9mis par google aux fins de mesurer l\u2019audience des diff\u00e9rents contenus et rubriques de notre site, afin de les \u00e9valuer et de mieux les organiser. Ces Cookies permettent \u00e9galement, le cas \u00e9ch\u00e9ant, de d\u00e9tecter des probl\u00e8mes de navigation et par cons\u00e9quent d\u2019am\u00e9liorer l\u2019ergonomie de nos services. Ces Cookies ne produisent que des statistiques anonymes et des volumes de fr\u00e9quentation, \u00e0 l\u2019exclusion de toute information individuelle.<\/p><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-656b9115 elementor-widget elementor-widget-shortcode\" data-id=\"656b9115\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<table id=\"tablepress-1\" class=\"tablepress tablepress-id-1\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Noms de cookies<\/th><th class=\"column-2\">Type de cookie<\/th><th class=\"column-3\">Fournisseur<\/th><th class=\"column-4\">Dur\u00e9e d\u2019expiration<\/th><th class=\"column-5\">Type<\/th><th class=\"column-6\">Objet<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">CookieConsent<\/td><td class=\"column-2\">N\u00e9cessaires<\/td><td class=\"column-3\">meetmeat.be<\/td><td class=\"column-4\">1an<\/td><td class=\"column-5\">HTTP<\/td><td class=\"column-6\">Stocke l'autorisation d'utilisation de cookies pour le domaine actuel par l'utilisateur<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">rc::a<\/td><td class=\"column-2\">N\u00e9cessaires<\/td><td class=\"column-3\">google.com<\/td><td class=\"column-4\">Persistent<\/td><td class=\"column-5\">HTML<\/td><td class=\"column-6\">Ce cookie est utilis\u00e9 pour distinguer les humains des robots. Ceci est b\u00e9n\u00e9fique pour le site web afin de cr\u00e9er des rapports valides sur l'utilisation du leur site.<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">rc::c<\/td><td class=\"column-2\">N\u00e9cessaires<\/td><td class=\"column-3\">google.com<\/td><td class=\"column-4\">Session<\/td><td class=\"column-5\">HTML<\/td><td class=\"column-6\">Ce cookie est utilis\u00e9 pour distinguer les humains des robots.<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">wp-settings-{user_id}<\/td><td class=\"column-2\">N\u00e9cessaires<\/td><td class=\"column-3\">meetmeat.be<\/td><td class=\"column-4\">1 an<\/td><td class=\"column-5\">HTTP<\/td><td class=\"column-6\">Utilis\u00e9 pour la persistance de la configuration wp-admin d\u2019un utilisateur. (utilisateur connect\u00e9 uniquement)<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">wordpress_test_cookie<\/td><td class=\"column-2\">N\u00e9cessaires<\/td><td class=\"column-3\">meetmeat.be<\/td><td class=\"column-4\">Session<\/td><td class=\"column-5\">HTTP<\/td><td class=\"column-6\">Teste que le navigateur accepte les cookies.<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">woocommerce_*, wp_woocommerce_*, wc_cart_hash_*, wc_fragments_*<\/td><td class=\"column-2\">N\u00e9cessaires<\/td><td class=\"column-3\">meetmeat.be<\/td><td class=\"column-4\">Persistent<\/td><td class=\"column-5\">HTTP<\/td><td class=\"column-6\">Permets d'enregistrer les paniers des utilisateurs afin de retrouver leur panier lorsque l'utilisateur revient sur le site.<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">wordpress_logged_in &amp; wordpress_sec<\/td><td class=\"column-2\">N\u00e9cessaires<\/td><td class=\"column-3\">meetmeat.be<\/td><td class=\"column-4\">14 jours si vous s\u00e9lectionnez \u00ab Se souvenir de moi \u00bb lorsque vous vous connectez. Sinon, la dur\u00e9e de la session.<\/td><td class=\"column-5\">HTTP<\/td><td class=\"column-6\">Utilis\u00e9 pour v\u00e9rifier si le visiteur actuel est connect\u00e9 comme un utilisateur. (utilisateur connect\u00e9 uniquement)<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">_ga<\/td><td class=\"column-2\">Statistiques<\/td><td class=\"column-3\">meetmeat.be<\/td><td class=\"column-4\">2 ans<\/td><td class=\"column-5\">HTTP<\/td><td class=\"column-6\">Enregistre un identifiant unique utilis\u00e9 pour g\u00e9n\u00e9rer des donn\u00e9es statistiques sur la fa\u00e7on dont le visiteur utilise le site.<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">_gat<\/td><td class=\"column-2\">Statistiques<\/td><td class=\"column-3\">meetmeat.be<\/td><td class=\"column-4\">1 jour<\/td><td class=\"column-5\">HTTP<\/td><td class=\"column-6\">Utilis\u00e9 par Google Analytics pour diminuer radicalement le taux de requ\u00eates<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">_gid<\/td><td class=\"column-2\">Statistiques<\/td><td class=\"column-3\">meetmeat.be<\/td><td class=\"column-4\">1 jour<\/td><td class=\"column-5\">HTTP<\/td><td class=\"column-6\">Enregistre un identifiant unique utilis\u00e9 pour g\u00e9n\u00e9rer des donn\u00e9es statistiques sur la fa\u00e7on dont le visiteur utilise le site.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-1 from cache --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b478fcf elementor-widget elementor-widget-text-editor\" data-id=\"6b478fcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: justify;\"><strong>Vos choix et modalit\u00e9s d\u2019opposition et suppression concernant les cookies sur nos sites<\/strong><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3434be26 elementor-widget elementor-widget-html\" data-id=\"3434be26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a style=\"cursor:pointer; color: #D80015;\" class=\"cky-banner-element\">Cliquez-ici pour modifier vos pr\u00e9f\u00e9rences en mati\u00e8re de cookies<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ea36ec5 elementor-widget elementor-widget-text-editor\" data-id=\"7ea36ec5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\">En utilisant notre site, vous consentez \u00e0 l\u2019utilisation des Cookies pr\u00e9cit\u00e9s. Vous pouvez toutefois choisir \u00e0 tout moment de les d\u00e9sactiver via votre navigateur ou en cliquant sur le bouton ci dessus. Celui-ci peut \u00e9galement \u00eatre param\u00e9tr\u00e9 pour vous signaler syst\u00e9matiquement les Cookies qui sont d\u00e9pos\u00e9s dans votre terminal et vous demander de les accepter ou pas.<\/p>\n<p style=\"text-align: justify;\">Si votre terminal est utilis\u00e9 par plusieurs personnes et lorsqu\u2019un m\u00eame terminal dispose de plusieurs logiciels de navigation, nous ne pouvons pas nous assurer de mani\u00e8re certaine que les services et publicit\u00e9s destin\u00e9s \u00e0 votre terminal correspondent bien \u00e0 votre propre utilisation de ce terminal et non \u00e0 celle d\u2019un autre utilisateur du terminal.<\/p>\n<p style=\"text-align: justify;\">Le cas \u00e9ch\u00e9ant, le partage avec d\u2019autres personnes de l\u2019utilisation de votre terminal et la configuration des param\u00e8tres de votre navigateur \u00e0 l\u2019\u00e9gard des Cookies rel\u00e8vent de votre libre choix et de votre responsabilit\u00e9.<\/p>\n\n<h4 id=\"refuser_nav\" class=\"h5_like\" style=\"text-align: justify;\"><strong>Refuser ou supprimer un Cookie par l\u2019interm\u00e9diaire de votre logiciel de navigation<\/strong><\/h4>\n<p style=\"text-align: justify;\">Si vous utilisez le navigateur Explorer : cliquez sur le bouton \u201cOutils\u201d, puis \u201cOptions Internet\u201d. Sous l\u2019onglet g\u00e9n\u00e9ral \u201cHistorique de navigation\u201d, cliquez sur \u201cParam\u00e8tres\u201d. Puis cliquez sur \u201cAfficher les fichiers\u201d et s\u00e9lectionnez le ou les Cookies que vous souhaitez d\u00e9sactiver. Fermez ensuite la fen\u00eatre qui contient cette liste de Cookies et cliquez deux fois sur \u201cOK\u201d pour retourner sur Internet.\n<a href=\"http:\/\/windows.microsoft.com\/fr-FR\/windows-vista\/Block-or-allow-cookies\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">cliquer ici<\/a><\/p>\n<p style=\"text-align: justify;\">Si vous utilisez le navigateur Firefox : cliquez sur l\u2019ic\u00f4ne du Menu Firefox, puis sur le bouton \u201cOutils\u201d, puis \u201cOptions\u201d ; dans la fen\u00eatre qui s\u2019affiche, choisissez \u201cVie Priv\u00e9e\u201d et cliquez sur \u201cSupprimez Cookies Sp\u00e9cifiques\u201d. S\u00e9lectionnez les Cookies que vous souhaitez d\u00e9sactiver puis supprimez-les.\n<a href=\"http:\/\/support.mozilla.org\/fr\/kb\/Activer%20et%20d%C3%A9sactiver%20les%20cookies\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">cliquer ici<\/a><\/p>\n<p style=\"text-align: justify;\">Si vous utilisez le navigateur Safari : cliquez sur le bouton \u201cParam\u00e8tres\u201d, puis \u201cPr\u00e9f\u00e9rences\u201d. Dans la fen\u00eatre qui s\u2019affiche, choisissez \u201cConfidentialit\u00e9\/S\u00e9curit\u00e9\u201d, et cliquez sur \u201cAfficher les Cookies\u201d. S\u00e9lectionnez les Cookies que vous souhaitez d\u00e9sactiver puis cliquez sur \u201cEffacer\u201d ou sur \u201cTout effacer\u201d.\n<a href=\"http:\/\/docs.info.apple.com\/article.html?path=Safari\/3.0\/fr\/9277.html\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"> cliquer ici<\/a><\/p>\n<p style=\"text-align: justify;\">Si vous utilisez le navigateur Chrome : cliquez sur l\u2019ic\u00f4ne du menu Google Chrome, puis \u201cParam\u00e8tres\u201d. Au bas de la page, cliquez sur \u201cAfficher les param\u00e8tres avanc\u00e9s\u201d. Dans la section \u201cConfidentialit\u00e9\u201d, cliquez sur \u201cParam\u00e8tre de contenus\u201d. Pour d\u00e9sactiver les Cookies :<\/p>\n\n<ul style=\"text-align: justify;\">\n \t<li>S\u00e9lectionnez \u201cInterdire \u00e0 tous les sites de stocker des donn\u00e9es\u201d<\/li>\n \t<li>Cliquez sur \u201cCookies et donn\u00e9es de site\u201d, puis passez la souris sur le site ayant cr\u00e9\u00e9 le Cookie, et cliquez sur \u201cX\u201d dans l\u2019angle droit, ou cliquez sur \u201cTout supprimer\u201d.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=fr&amp;hlrm=en&amp;answer=95647\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">cliquer ici<\/a><\/p>\n\n<h4 id=\"refuser_rsocial\" class=\"h5_like\" style=\"text-align: justify;\"><strong>Refuser un Cookie \u00e9mis par un r\u00e9seau social<\/strong><\/h4>\n<p style=\"text-align: justify;\">Si vous souhaitez interagir sur les Cookies des r\u00e9seaux sociaux de nos sites, nous vous invitons \u00e0 consulter la documentation sur le site des \u00e9diteurs sociaux :<\/p>\n<p style=\"text-align: justify;\">Google+ :\u00a0<a href=\"https:\/\/support.google.com\/accounts\/answer\/61416?hl=fr\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">cliquer ici<\/a>\nTwitter :\u00a0<a href=\"https:\/\/support.twitter.com\/articles\/20171379-twitter-prend-en-charge-la-desactivation-du-suivi-dnt#\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">cliquer ici<\/a>\nLinkedIn :\u00a0<a href=\"http:\/\/www.linkedin.com\/legal\/cookie-policy\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">cliquer ici<\/a>\nFacebook :\u00a0<a href=\"https:\/\/www.facebook.com\/help\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">cliquer ici<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c891b62 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c891b62\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61a244eb\" data-id=\"61a244eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55e54fa8 elementor-widget elementor-widget-heading\" data-id=\"55e54fa8\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"confidentialite\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">III. POLITIQUE DE CONFIDENTIALIT\u00c9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cd0e2b8 elementor-widget elementor-widget-text-editor\" data-id=\"1cd0e2b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column wpb_content_element \"><div class=\"wpb_wrapper\"><p>meatmeat.be collecte des donn\u00e9es telles que des<a href=\"https:\/rgpd\/#cookies\"> cookies<\/a>, votre nom, pr\u00e9nom, nom d\u2019entreprise, email, code postal, url site web et num\u00e9ro de t\u00e9l\u00e9phone lors de la prise de rendez-vous, r\u00e9servation en ligne, achat en ligne, demande de contact par formulaire ou d\u2019inscription \u00e0 nos newsletters.<\/p><p>Vous \u00eates libre de refuser cette collecte de donn\u00e9es en d\u00e9sactivant les cookies, ou en nous contactant par d\u2019autres moyens que le formulaire de contact.<\/p><p>meatmeat.be ne pourra \u00eatre tenu responsable au cas o\u00f9 un tiers obtient d\u2019une mani\u00e8re ill\u00e9gale un acc\u00e8s \u00e0 notre syst\u00e8me et \u00e0 vos donn\u00e9es priv\u00e9es. Cependant meatmeat.be met tout en \u0153uvre pour garantir la s\u00e9curit\u00e9 de vos donn\u00e9es et ses bases de donn\u00e9es et s\u2019engage \u00e0 ne pas divulguer vos donn\u00e9es priv\u00e9es \u00e0 d\u2019autres soci\u00e9t\u00e9s ou entreprises sans votre accord.<\/p><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20d57665 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20d57665\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f4a1d3\" data-id=\"7f4a1d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b33034 elementor-widget elementor-widget-heading\" data-id=\"7b33034\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"mentions\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">IV. MENTIONS L\u00c9GALES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e773814 elementor-widget elementor-widget-text-editor\" data-id=\"6e773814\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSoci\u00e9t\u00e9 : Noryel S.R.L.<\/br>\n\nAdresse: 124 rue Stevin, 1000 Brussels<\/br>\n\nT\u00e9l\u00e9phone: +32 (0)2 231 07 42<\/br>\n\nEmail: schuman@meetmeat.be<\/br>\n\nH\u00e9berg\u00e9 par: Step2web SRL via OVH\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Meet Meat RGPD I. Conditions g\u00e9n\u00e9rales d&rsquo;utilisation Mise \u00e0 jour le: 01\/04\/2024 1. Champ d&rsquo;application Les pr\u00e9sentes conditions g\u00e9n\u00e9rales d&rsquo;utilisation (ci-apr\u00e8s les \u00ab\u00a0CGU\u00a0\u00bb) sont conclues par : ayant son si\u00e8ge social \u00e0 , enregistr\u00e9 \u00e0 la BCE sous le num\u00e9ro , ci-apr\u00e8s d\u00e9nomm\u00e9 et s&rsquo;appliquent \u00e0 toute visite ou utilisation du site internet (ci-apr\u00e8s \u00ab\u00a0Plateforme\u00a0\u00bb) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":679,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-785","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rgpd - Meet Meat<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rgpd - Meet Meat\" \/>\n<meta property=\"og:description\" content=\"Meet Meat RGPD I. Conditions g\u00e9n\u00e9rales d&rsquo;utilisation Mise \u00e0 jour le: 01\/04\/2024 1. Champ d&rsquo;application Les pr\u00e9sentes conditions g\u00e9n\u00e9rales d&rsquo;utilisation (ci-apr\u00e8s les \u00ab\u00a0CGU\u00a0\u00bb) sont conclues par : ayant son si\u00e8ge social \u00e0 , enregistr\u00e9 \u00e0 la BCE sous le num\u00e9ro , ci-apr\u00e8s d\u00e9nomm\u00e9 et s&rsquo;appliquent \u00e0 toute visite ou utilisation du site internet (ci-apr\u00e8s \u00ab\u00a0Plateforme\u00a0\u00bb) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meetmeat.be\/fr\/rgpd\/\" \/>\n<meta property=\"og:site_name\" content=\"Meet Meat\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-06T09:44:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/meetmeat.be\/wp-content\/uploads\/2024\/04\/meet_meat-steak-house-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1331\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/meetmeat.be\\\/fr\\\/rgpd\\\/\",\"url\":\"https:\\\/\\\/meetmeat.be\\\/fr\\\/rgpd\\\/\",\"name\":\"Rgpd - Meet Meat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meetmeat.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/meetmeat.be\\\/fr\\\/rgpd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/meetmeat.be\\\/fr\\\/rgpd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/meetmeat.be\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/meet_meat-steak-house-3.jpg\",\"datePublished\":\"2024-04-24T07:08:50+00:00\",\"dateModified\":\"2024-05-06T09:44:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meetmeat.be\\\/fr\\\/rgpd\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/meetmeat.be\\\/fr\\\/rgpd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/meetmeat.be\\\/fr\\\/rgpd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/meetmeat.be\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/meet_meat-steak-house-3.jpg\",\"contentUrl\":\"https:\\\/\\\/meetmeat.be\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/meet_meat-steak-house-3.jpg\",\"width\":2000,\"height\":1331},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meetmeat.be\\\/fr\\\/rgpd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/meetmeat.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rgpd\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meetmeat.be\\\/#website\",\"url\":\"https:\\\/\\\/meetmeat.be\\\/\",\"name\":\"Meet Meat\",\"description\":\"Steak and Wine House\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meetmeat.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rgpd - Meet Meat","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Rgpd - Meet Meat","og_description":"Meet Meat RGPD I. Conditions g\u00e9n\u00e9rales d&rsquo;utilisation Mise \u00e0 jour le: 01\/04\/2024 1. Champ d&rsquo;application Les pr\u00e9sentes conditions g\u00e9n\u00e9rales d&rsquo;utilisation (ci-apr\u00e8s les \u00ab\u00a0CGU\u00a0\u00bb) sont conclues par : ayant son si\u00e8ge social \u00e0 , enregistr\u00e9 \u00e0 la BCE sous le num\u00e9ro , ci-apr\u00e8s d\u00e9nomm\u00e9 et s&rsquo;appliquent \u00e0 toute visite ou utilisation du site internet (ci-apr\u00e8s \u00ab\u00a0Plateforme\u00a0\u00bb) [&hellip;]","og_url":"https:\/\/meetmeat.be\/fr\/rgpd\/","og_site_name":"Meet Meat","article_modified_time":"2024-05-06T09:44:55+00:00","og_image":[{"width":2000,"height":1331,"url":"https:\/\/meetmeat.be\/wp-content\/uploads\/2024\/04\/meet_meat-steak-house-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/meetmeat.be\/fr\/rgpd\/","url":"https:\/\/meetmeat.be\/fr\/rgpd\/","name":"Rgpd - Meet Meat","isPartOf":{"@id":"https:\/\/meetmeat.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/meetmeat.be\/fr\/rgpd\/#primaryimage"},"image":{"@id":"https:\/\/meetmeat.be\/fr\/rgpd\/#primaryimage"},"thumbnailUrl":"https:\/\/meetmeat.be\/wp-content\/uploads\/2024\/04\/meet_meat-steak-house-3.jpg","datePublished":"2024-04-24T07:08:50+00:00","dateModified":"2024-05-06T09:44:55+00:00","breadcrumb":{"@id":"https:\/\/meetmeat.be\/fr\/rgpd\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/meetmeat.be\/fr\/rgpd\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/meetmeat.be\/fr\/rgpd\/#primaryimage","url":"https:\/\/meetmeat.be\/wp-content\/uploads\/2024\/04\/meet_meat-steak-house-3.jpg","contentUrl":"https:\/\/meetmeat.be\/wp-content\/uploads\/2024\/04\/meet_meat-steak-house-3.jpg","width":2000,"height":1331},{"@type":"BreadcrumbList","@id":"https:\/\/meetmeat.be\/fr\/rgpd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/meetmeat.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Rgpd"}]},{"@type":"WebSite","@id":"https:\/\/meetmeat.be\/#website","url":"https:\/\/meetmeat.be\/","name":"Meet Meat","description":"Steak and Wine House","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meetmeat.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/meetmeat.be\/fr\/wp-json\/wp\/v2\/pages\/785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meetmeat.be\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/meetmeat.be\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/meetmeat.be\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meetmeat.be\/fr\/wp-json\/wp\/v2\/comments?post=785"}],"version-history":[{"count":4,"href":"https:\/\/meetmeat.be\/fr\/wp-json\/wp\/v2\/pages\/785\/revisions"}],"predecessor-version":[{"id":1016,"href":"https:\/\/meetmeat.be\/fr\/wp-json\/wp\/v2\/pages\/785\/revisions\/1016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meetmeat.be\/fr\/wp-json\/wp\/v2\/media\/679"}],"wp:attachment":[{"href":"https:\/\/meetmeat.be\/fr\/wp-json\/wp\/v2\/media?parent=785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}